{"id":2643,"date":"2013-05-30T20:52:37","date_gmt":"2013-05-30T17:52:37","guid":{"rendered":"http:\/\/www.saitem.org\/2013t\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1.jpg"},"modified":"2013-05-30T20:52:37","modified_gmt":"2013-05-30T17:52:37","slug":"969869_10151608744242372_166837425_n-2","status":"inherit","type":"attachment","link":"https:\/\/www.saitem.org\/tr\/yogun-yagis-altinda-test-turlari\/969869_10151608744242372_166837425_n-2\/","title":{"rendered":"969869_10151608744242372_166837425_n"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1.jpg'><img width=\"300\" height=\"200\" src=\"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-300x200.jpg 300w, https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":640,"file":"2013\/05\/969869_10151608744242372_166837425_n1.jpg","sizes":{"thumbnail":{"file":"969869_10151608744242372_166837425_n1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-150x150.jpg"},"medium":{"file":"969869_10151608744242372_166837425_n1-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-300x200.jpg"},"featured":{"file":"969869_10151608744242372_166837425_n1-700x426.jpg","width":700,"height":426,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-700x426.jpg"},"blog-one":{"file":"969869_10151608744242372_166837425_n1-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-300x300.jpg"},"small-square":{"file":"969869_10151608744242372_166837425_n1-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-50x50.jpg"},"half-landscape":{"file":"969869_10151608744242372_166837425_n1-290x166.jpg","width":290,"height":166,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-290x166.jpg"},"blog-full-width":{"file":"969869_10151608744242372_166837425_n1-620x310.jpg","width":620,"height":310,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-620x310.jpg"},"featured-image":{"file":"969869_10151608744242372_166837425_n1-620x350.jpg","width":620,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-620x350.jpg"},"gallery-links":{"file":"969869_10151608744242372_166837425_n1-186x186.jpg","width":186,"height":186,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-186x186.jpg"},"blog-three":{"file":"969869_10151608744242372_166837425_n1-620x220.jpg","width":620,"height":220,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1-620x220.jpg"},"full":{"file":"969869_10151608744242372_166837425_n1.jpg","width":960,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":2631,"source_url":"https:\/\/www.saitem.org\/tr\/wp-content\/uploads\/2013\/05\/969869_10151608744242372_166837425_n1.jpg","_links":{"self":[{"href":"https:\/\/www.saitem.org\/tr\/wp-json\/wp\/v2\/media\/2643"}],"collection":[{"href":"https:\/\/www.saitem.org\/tr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.saitem.org\/tr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.saitem.org\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saitem.org\/tr\/wp-json\/wp\/v2\/comments?post=2643"}]}}